{"id":4703,"date":"2023-12-28T17:41:08","date_gmt":"2023-12-28T15:41:08","guid":{"rendered":"https:\/\/lavega.gr\/product\/yerba-mate-rosamonte-500g\/"},"modified":"2026-04-23T16:45:19","modified_gmt":"2026-04-23T14:45:19","slug":"yerba-mate-rosamonte-500g","status":"publish","type":"product","link":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/","title":{"rendered":"Yerba Mate \u2018Rosamonte\u2019 (500g)"},"content":{"rendered":"<p><strong>Qu\u00e9 es:<\/strong> La yerba mate Rosamonte es la cl\u00e1sica y tradicional &#8220;gigante&#8221; de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha sido a\u00f1ejada con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico. <\/p>\n<p><b data-path-to-node=\"5\" data-index-in-node=\"280\">Consejo de La Vega<\/b>: \u00a1La mejor opci\u00f3n para empezar el d\u00eda! Su intenso sabor te despertar\u00e1 y te mantendr\u00e1 lleno de energ\u00eda durante horas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 es: La yerba mate Rosamonte es la cl\u00e1sica y tradicional &#8220;gigante&#8221; de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha sido a\u00f1ejada con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico. Consejo de La Vega: \u00a1La mejor opci\u00f3n para empezar el d\u00eda! Su intenso sabor te despertar\u00e1&#8230;<\/p>\n","protected":false},"featured_media":4702,"template":"","meta":[],"product_cat":[93,89],"product_tag":[],"class_list":{"0":"post-4703","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-gluten","7":"product_cat-bebidas-tropicales-y-cafe","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega<\/title>\n<meta name=\"description\" content=\"La yerba mate Rosamonte es la cl\u00e1sica y tradicional &quot;gigante&quot; de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega\" \/>\n<meta property=\"og:description\" content=\"La yerba mate Rosamonte es la cl\u00e1sica y tradicional &quot;gigante&quot; de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/\" \/>\n<meta property=\"og:site_name\" content=\"La Vega\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T14:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/\",\"url\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/\",\"name\":\"Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega\",\"isPartOf\":{\"@id\":\"https:\/\/lavega.gr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png\",\"datePublished\":\"2023-12-28T15:41:08+00:00\",\"dateModified\":\"2026-04-23T14:45:19+00:00\",\"description\":\"La yerba mate Rosamonte es la cl\u00e1sica y tradicional \\\"gigante\\\" de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.\",\"breadcrumb\":{\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage\",\"url\":\"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png\",\"contentUrl\":\"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lavega.gr\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/lavega.gr\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yerba Mate \u2018Rosamonte\u2019 (500g)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lavega.gr\/#website\",\"url\":\"https:\/\/lavega.gr\/\",\"name\":\"La Vega\",\"description\":\"Productos Latinos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lavega.gr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega","description":"La yerba mate Rosamonte es la cl\u00e1sica y tradicional \"gigante\" de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/","og_locale":"es_ES","og_type":"article","og_title":"Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega","og_description":"La yerba mate Rosamonte es la cl\u00e1sica y tradicional \"gigante\" de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.","og_url":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/","og_site_name":"La Vega","article_modified_time":"2026-04-23T14:45:19+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/","url":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/","name":"Yerba Mate \u2018Rosamonte\u2019 (500g) | La Vega","isPartOf":{"@id":"https:\/\/lavega.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage"},"image":{"@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage"},"thumbnailUrl":"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png","datePublished":"2023-12-28T15:41:08+00:00","dateModified":"2026-04-23T14:45:19+00:00","description":"La yerba mate Rosamonte es la cl\u00e1sica y tradicional \"gigante\" de Argentina. Es una yerba mate fuerte con tallos (con palo), que ha madurado con palo de rosa, adquiriendo un aroma caracter\u00edstico, intenso y ligeramente r\u00fastico.","breadcrumb":{"@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#primaryimage","url":"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png","contentUrl":"https:\/\/lavega.gr\/wp-content\/uploads\/2023\/12\/yerba-mate-rosamonte-500g.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/lavega.gr\/es\/producto\/yerba-mate-rosamonte-500g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lavega.gr\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lavega.gr\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Yerba Mate \u2018Rosamonte\u2019 (500g)"}]},{"@type":"WebSite","@id":"https:\/\/lavega.gr\/#website","url":"https:\/\/lavega.gr\/","name":"La Vega","description":"Productos Latinos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavega.gr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/product\/4703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/media\/4702"}],"wp:attachment":[{"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/media?parent=4703"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/product_cat?post=4703"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lavega.gr\/es\/wp-json\/wp\/v2\/product_tag?post=4703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}